
{"id":21513,"date":"2023-11-01T17:12:22","date_gmt":"2023-11-01T16:12:22","guid":{"rendered":"https:\/\/projects.grupomainjobs.com\/?p=21513"},"modified":"2024-08-05T10:16:27","modified_gmt":"2024-08-05T09:16:27","slug":"mainjobs-lanza-13-000-plazas-de-formacion-online-en-colaboracion-con-el-ministerio-de-trabajo-para-personas-trabajadoras-autonomas-y-emprendedoras-de-diferentes-sectores","status":"publish","type":"post","link":"https:\/\/projects.grupomainjobs.com\/ca\/mainjobs-lanza-13-000-plazas-de-formacion-online-en-colaboracion-con-el-ministerio-de-trabajo-para-personas-trabajadoras-autonomas-y-emprendedoras-de-diferentes-sectores\/","title":{"rendered":"Mainjobs llan\u00e7a 13.000 places de formaci\u00f3 en l\u00ednia en col\u00b7laboraci\u00f3 amb el Ministeri de Treball per a persones treballadores, aut\u00f2nomes i emprenedores de diferents sectors"},"content":{"rendered":"<h2 class=\"gb-headline gb-headline-f1d1a353 gb-headline-text\">Mainjobs llan\u00e7a 13.000 places de formaci\u00f3<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Mainjobs ha dissenyat i posat a la disposici\u00f3 de la ciutadania diferents plans de formaci\u00f3 gratu\u00efts en col\u00b7laboraci\u00f3 amb el Ministeri de Treball i el Servei P\u00fablic d&#039;Ocupaci\u00f3 Estatal. <strong>Podran beneficiar-se d&#039;aquesta iniciativa 13.000 persones treballadores a Espanya, amb l&#039;objectiu de continuar avan\u00e7ant en la carrera professional, adquirir noves compet\u00e8ncies i actualitzar les seves habilitats i coneixements a la realitat del teixit empresarial.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aquesta oferta formativa est\u00e0 constitu\u00efda per <strong>m\u00e9s d&#039;un centenar de cursos en l\u00ednia<\/strong>, creats per a professionals de sectors com comer\u00e7 i m\u00e0rqueting, construcci\u00f3, formaci\u00f3 i educaci\u00f3, gran distribuci\u00f3, ind\u00fastria aliment\u00e0ria, serveis B2B, serveis mediambientals, administraci\u00f3 i gesti\u00f3 o hostaleria.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLa formaci\u00f3 cont\u00ednua \u00e9s l&#039;eina clau de qu\u00e8 disposen empreses i persones aut\u00f2nomes per mantenir-se en el millor moment professional i aconseguir adaptar-se a mercats en constant evoluci\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"gb-block-image gb-block-image-962896c5\"><img fetchpriority=\"high\" decoding=\"async\" width=\"626\" height=\"418\" class=\"gb-image gb-image-962896c5\" src=\"https:\/\/projects.grupomainjobs.com\/wp-content\/uploads\/2023\/11\/Formacion.avif\" alt=\"Formacion\" title=\"Formaci\u00f3\" srcset=\"https:\/\/projects.grupomainjobs.com\/wp-content\/uploads\/2023\/11\/Formacion.avif 626w, https:\/\/projects.grupomainjobs.com\/wp-content\/uploads\/2023\/11\/Formacion-300x200.avif 300w, https:\/\/projects.grupomainjobs.com\/wp-content\/uploads\/2023\/11\/Formacion-18x12.avif 18w, https:\/\/projects.grupomainjobs.com\/wp-content\/uploads\/2023\/11\/Formacion-500x334.avif 500w\" sizes=\"(max-width: 626px) 100vw, 626px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>A <a href=\"https:\/\/projects.grupomainjobs.com\/\">Mainjobs<\/a> col\u00b7laborem amb l&#039;administraci\u00f3 p\u00fablica per a la capacitaci\u00f3 professional multisectorial des de fa d\u00e8cades<\/strong>, per aix\u00f2 el llan\u00e7ament d&#039;aquesta nova convocat\u00f2ria suposa un repte que assumim amb il\u00b7lusi\u00f3 i amb totes les eines necess\u00e0ries per aportar a l&#039;alumnat una experi\u00e8ncia satisfact\u00f2ria\u201d. \u2013 Afirma Mar\u00eda J\u00e1imez, una de les directores que lidera aquest ambici\u00f3s projecte a Mainjobs.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Finan\u00e7ant aquest tipus de formaci\u00f3, el SEPE assegura la garantia de lexercici del dret a la formaci\u00f3 de les persones treballadores. Segons l&#039;INE, <strong>el nombre de persones ocupades a Espanya actualment se situa a 21.056.700, la xifra hist\u00f2rica m\u00e9s alta recollida per l&#039;Institut.<\/strong> Ens trobem, aix\u00ed, davant d&#039;una situaci\u00f3 sense precedents en qu\u00e8 hem de facilitar a aquest col\u00b7lectiu els recursos necessaris per desenvolupar la seva activitat professional amb \u00e8xit.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les persones interessades a formar-se poden triar el curs que millor s&#039;adapti a les seves necessitats i inscriure&#039;s a <a href=\"https:\/\/cursosgratis.projects.grupomainjobs.com\/sector\/otros\/\" target=\"_blank\" rel=\"noreferrer noopener\">cursosgratis.projects.grupomainjobs.com<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Mainjobs lanza 13.000 plazas de formaci\u00f3n Mainjobs ha dise\u00f1ado y puesto a disposici\u00f3n de la ciudadan\u00eda diferentes planes de formaci\u00f3n gratuitos en colaboraci\u00f3n con el Ministerio de Trabajo y el [&hellip;]<\/p>\n","protected":false},"author":9192271,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","_joinchat":[],"footnotes":""},"categories":[254],"tags":[37],"class_list":["post-21513","post","type-post","status-publish","format-standard","hentry","category-nuestro-blog","tag-formacion-2"],"acf":[],"author_meta":{"display_name":"Comunicaci\u00f3n Mainjobs","author_link":"http:\/\/www.projects.grupomainjobs.com"},"featured_img":null,"coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/projects.grupomainjobs.com\/ca\/nuestro-blog\/\" class=\"advgb-post-tax-term\">Blog<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Blog<\/span>"]},"tags":{"linked":["<a href=\"https:\/\/projects.grupomainjobs.com\/ca\/nuestro-blog\/\" class=\"advgb-post-tax-term\">formaci\u00f3n<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">formaci\u00f3n<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Posted 3 anys ago","modified":"Updated 2 anys ago"},"absolute_dates":{"created":"Posted on novembre 1, 2023","modified":"Updated on agost 5, 2024"},"absolute_dates_time":{"created":"Posted on novembre 1, 2023 17:12","modified":"Updated on agost 5, 2024 10:16"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/projects.grupomainjobs.com\/ca\/wp-json\/wp\/v2\/posts\/21513","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/projects.grupomainjobs.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/projects.grupomainjobs.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/projects.grupomainjobs.com\/ca\/wp-json\/wp\/v2\/users\/9192271"}],"replies":[{"embeddable":true,"href":"https:\/\/projects.grupomainjobs.com\/ca\/wp-json\/wp\/v2\/comments?post=21513"}],"version-history":[{"count":4,"href":"https:\/\/projects.grupomainjobs.com\/ca\/wp-json\/wp\/v2\/posts\/21513\/revisions"}],"predecessor-version":[{"id":26945,"href":"https:\/\/projects.grupomainjobs.com\/ca\/wp-json\/wp\/v2\/posts\/21513\/revisions\/26945"}],"wp:attachment":[{"href":"https:\/\/projects.grupomainjobs.com\/ca\/wp-json\/wp\/v2\/media?parent=21513"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/projects.grupomainjobs.com\/ca\/wp-json\/wp\/v2\/categories?post=21513"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/projects.grupomainjobs.com\/ca\/wp-json\/wp\/v2\/tags?post=21513"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}